{"id":80,"count":1,"description":"","link":"https:\/\/cavinenterprise.com\/ja\/tag\/refined-sesame-oil-for-import-and-export\/","name":"Refined Sesame Oil for Import and Export","slug":"refined-sesame-oil-for-import-and-export","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/cavinenterprise.com\/ja\/wp-json\/wp\/v2\/tags\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cavinenterprise.com\/ja\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/cavinenterprise.com\/ja\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/cavinenterprise.com\/ja\/wp-json\/wp\/v2\/posts?tags=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}